{"id":261,"count":1,"description":"","link":"https:\/\/www.inmediatodigital.com\/index.php\/category\/tecnologia\/","name":"TECNOLOG\u00cdA","slug":"tecnologia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.inmediatodigital.com\/index.php\/wp-json\/wp\/v2\/categories\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inmediatodigital.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.inmediatodigital.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.inmediatodigital.com\/index.php\/wp-json\/wp\/v2\/posts?categories=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}